{"id":1058,"date":"2023-04-23T06:12:02","date_gmt":"2023-04-23T06:12:02","guid":{"rendered":"https:\/\/cozystay.loftocean.com\/apartment\/custom-block\/copied-offcanvas-menu\/"},"modified":"2025-12-10T14:54:50","modified_gmt":"2025-12-10T14:54:50","slug":"offcanvas-menu","status":"publish","type":"custom_blocks","link":"https:\/\/casadovereador.com\/en\/custom-block\/offcanvas-menu\/","title":{"rendered":"Offcanvas Menu"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1058\" class=\"elementor elementor-1058\" data-elementor-post-type=\"custom_blocks\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-1517694b elementor-section-content-middle elementor-hidden-tablet elementor-hidden-mobile cs-section-content-fullwidth elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1517694b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-41df6ddd dark-color\" data-id=\"41df6ddd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fecbba3 elementor-widget elementor-widget-text-editor\" data-id=\"2fecbba3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/maps\/place\/Times+Square\/@40.757975,-73.985543,14z\/data=!4m6!3m5!1s0x89c25855c6480299:0x55194ec5a1ae072e!8m2!3d40.7579747!4d-73.9855426!16zL20vMDdxZHI?hl=en\" target=\"_blank\" rel=\"noopener\">1250 West 6th Ave,\nNew York, NY 10036,\nUnited States<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-75ccbf40 dark-color\" data-id=\"75ccbf40\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77cf7f3b elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"77cf7f3b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<a href=\"tel:+12125556688\">Tel: +1 212 555 6688<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1156d726 elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"1156d726\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Fax: +1 212 555 6699<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15719cfe elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"15719cfe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<a href=\"mailto:booking@cozystay.com\">booking@cozystay.com<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7c4be910 elementor-section-content-middle cs-section-content-fullwidth elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c4be910\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4891c44a dark-color\" data-id=\"4891c44a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41685404 elementor-widget__width-auto elementor-widget elementor-widget-cs_menu_toggle\" data-id=\"41685404\" data-element_type=\"widget\" data-widget_type=\"cs_menu_toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <button class=\"menu-toggle elementor-widget-menu-toggle close-button\">\n\t\t\t<span class=\"screen-reader-text\">Menu<\/span>\n\t\t\t<span class=\"menu-toggle-icon\"><\/span>\n\t\t\t\t\t<\/button>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2f8981cf dark-color\" data-id=\"2f8981cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3780a96 elementor-align-center elementor-widget elementor-widget-cs_logo\" data-id=\"3780a96\" data-element_type=\"widget\" data-widget_type=\"cs_logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                <a href=\"https:\/\/casadovereador.com\/en\/\" aria-label=\"Site Logo Image\">                    <img fetchpriority=\"high\" decoding=\"async\" width=\"1449\" height=\"1164\" src=\"https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7.png\" class=\"attachment-full size-full wp-image-1748\" alt=\"\" srcset=\"https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7.png 1449w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-300x241.png 300w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-1024x823.png 1024w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-768x617.png 768w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-1440x1157.png 1440w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-1200x964.png 1200w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-780x627.png 780w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-600x482.png 600w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-550x442.png 550w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-370x297.png 370w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-255x205.png 255w\" sizes=\"(max-width: 1449px) 100vw, 1449px\" \/>                <\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-27079465 dark-color\" data-id=\"27079465\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e55a43c elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"e55a43c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/cozystay.loftocean.com\/island-resort\/#\">EN<\/a>\u00a0\/\u00a0<a href=\"https:\/\/cozystay.loftocean.com\/island-resort\/#\">FR<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-975cb4c elementor-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"975cb4c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/casa-do-vereador.amenitiz.io\/pt\/booking\/room#DatesGuests-BE\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Check Availability<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-294813d1 elementor-section-content-middle elementor-hidden-desktop cs-section-content-fullwidth elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"294813d1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-256d09c7 dark-color\" data-id=\"256d09c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dce6217 elementor-widget__width-auto elementor-widget elementor-widget-cs_menu_toggle\" data-id=\"6dce6217\" data-element_type=\"widget\" data-widget_type=\"cs_menu_toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <button class=\"menu-toggle elementor-widget-menu-toggle close-button\">\n\t\t\t<span class=\"screen-reader-text\">Menu<\/span>\n\t\t\t<span class=\"menu-toggle-icon\"><\/span>\n\t\t\t\t\t<\/button>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4e740846 dark-color\" data-id=\"4e740846\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abbbfeb elementor-align-center elementor-widget elementor-widget-cs_logo\" data-id=\"abbbfeb\" data-element_type=\"widget\" data-widget_type=\"cs_logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                <a href=\"https:\/\/casadovereador.com\/en\/\" aria-label=\"Site Logo Image\">                    <img fetchpriority=\"high\" decoding=\"async\" width=\"1449\" height=\"1164\" src=\"https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7.png\" class=\"attachment-full size-full wp-image-1748\" alt=\"\" srcset=\"https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7.png 1449w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-300x241.png 300w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-1024x823.png 1024w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-768x617.png 768w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-1440x1157.png 1440w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-1200x964.png 1200w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-780x627.png 780w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-600x482.png 600w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-550x442.png 550w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-370x297.png 370w, https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7-255x205.png 255w\" sizes=\"(max-width: 1449px) 100vw, 1449px\" \/>                <\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1fae9a7d dark-color\" data-id=\"1fae9a7d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f4b46ed elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"2f4b46ed\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/casadovereador.com\/\">PT<\/a> \/ <a href=\"https:\/\/casadovereador.com\/en\/\">EN<\/a> \/ <a href=\"https:\/\/casadovereador.com\/es\/\">ES<\/a> \/ <a href=\"https:\/\/casadovereador.com\/fr\/\">FR<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-1a9c7992 cs-section-content-fullwidth elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a9c7992\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-20d9e6b0 dark-color\" data-id=\"20d9e6b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12ce81a1 elementor-widget elementor-widget-cs_menu\" data-id=\"12ce81a1\" data-element_type=\"widget\" data-widget_type=\"cs_menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"cs-menu cs-menu-mobile text-center-mobile text-center-tablet\"><ul id=\"menu-12ce81a1\" class=\"menu mobile-menu\"><li id=\"menu-item-1038\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1038\"><a href=\"https:\/\/casadovereador.com\/alojamentos\/\"><span>Accomodations<\/span><\/a><\/li>\n<li id=\"menu-item-279\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-279\"><a href=\"https:\/\/casadovereador.com\/sobre-nos\/\"><span>About us<\/span><\/a><\/li>\n<li id=\"menu-item-280\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-280\"><a href=\"https:\/\/casadovereador.com\/contatos\/\"><span>Contacts<\/span><\/a><\/li>\n<\/ul><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-20cd814 e-con-full e-flex e-con e-parent\" data-id=\"20cd814\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/casa-do-vereador.amenitiz.io\/pt\/booking\/room#DatesGuests-BE\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87a8feb elementor-widget elementor-widget-text-editor\" data-id=\"87a8feb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tCheck Availability\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8698d6b dark-color\" data-id=\"8698d6b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c494c30 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c494c30\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R. de Lisboa 14 A, 9500-216 Ponta Delgada<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+351966348336\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+351 966 348 336<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+351910208404\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+351 910 208 404<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:geral@casadovereador.com\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">geral@casadovereador.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"template":"","custom_blocks_category":[23],"class_list":["post-1058","custom_blocks","type-custom_blocks","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.3 (Yoast SEO v21.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Offcanvas Menu - Casa do Vereador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadovereador.com\/custom-block\/offcanvas-menu\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offcanvas Menu\" \/>\n<meta property=\"og:description\" content=\"1250 West 6th Ave, New York, NY 10036, United StatesTel: +1 212 555 6688 Fax: +1 212 555 6699 booking@cozystay.com Menu EN\u00a0\/\u00a0FR Menu PT \/ EN \/ ES \/ FR Alojamentos Sobre N\u00f3s Blog Contatos R. de Lisboa 14 A, 9500-216 Ponta Delgada +351 966 348 336 +351 910 208 404 geral@casadovereador.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadovereador.com\/custom-block\/offcanvas-menu\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa do Vereador\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T14:54:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casadovereador.com\/custom-block\/offcanvas-menu\/\",\"url\":\"https:\/\/casadovereador.com\/custom-block\/offcanvas-menu\/\",\"name\":\"Offcanvas Menu - Casa do Vereador\",\"isPartOf\":{\"@id\":\"https:\/\/casadovereador.com\/#website\"},\"datePublished\":\"2023-04-23T06:12:02+00:00\",\"dateModified\":\"2025-12-10T14:54:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/casadovereador.com\/custom-block\/offcanvas-menu\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casadovereador.com\/custom-block\/offcanvas-menu\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casadovereador.com\/custom-block\/offcanvas-menu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/casadovereador.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Offcanvas Menu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casadovereador.com\/#website\",\"url\":\"https:\/\/casadovereador.com\/\",\"name\":\"Casa do Vereador\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casadovereador.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Offcanvas Menu - Casa do Vereador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadovereador.com\/custom-block\/offcanvas-menu\/","og_locale":"en_US","og_type":"article","og_title":"Offcanvas Menu","og_description":"1250 West 6th Ave, New York, NY 10036, United StatesTel: +1 212 555 6688 Fax: +1 212 555 6699 booking@cozystay.com Menu EN\u00a0\/\u00a0FR Menu PT \/ EN \/ ES \/ FR Alojamentos Sobre N\u00f3s Blog Contatos R. de Lisboa 14 A, 9500-216 Ponta Delgada +351 966 348 336 +351 910 208 404 geral@casadovereador.com","og_url":"https:\/\/casadovereador.com\/custom-block\/offcanvas-menu\/","og_site_name":"Casa do Vereador","article_modified_time":"2025-12-10T14:54:50+00:00","og_image":[{"url":"https:\/\/casadovereador.com\/wp-content\/uploads\/2023\/03\/d47179013e00f948ca769fd9918722002a1ed6e7.png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casadovereador.com\/custom-block\/offcanvas-menu\/","url":"https:\/\/casadovereador.com\/custom-block\/offcanvas-menu\/","name":"Offcanvas Menu - Casa do Vereador","isPartOf":{"@id":"https:\/\/casadovereador.com\/#website"},"datePublished":"2023-04-23T06:12:02+00:00","dateModified":"2025-12-10T14:54:50+00:00","breadcrumb":{"@id":"https:\/\/casadovereador.com\/custom-block\/offcanvas-menu\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadovereador.com\/custom-block\/offcanvas-menu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/casadovereador.com\/custom-block\/offcanvas-menu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadovereador.com\/en\/"},{"@type":"ListItem","position":2,"name":"Offcanvas Menu"}]},{"@type":"WebSite","@id":"https:\/\/casadovereador.com\/#website","url":"https:\/\/casadovereador.com\/","name":"Casa do Vereador","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadovereador.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/casadovereador.com\/en\/wp-json\/wp\/v2\/custom_blocks\/1058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadovereador.com\/en\/wp-json\/wp\/v2\/custom_blocks"}],"about":[{"href":"https:\/\/casadovereador.com\/en\/wp-json\/wp\/v2\/types\/custom_blocks"}],"version-history":[{"count":8,"href":"https:\/\/casadovereador.com\/en\/wp-json\/wp\/v2\/custom_blocks\/1058\/revisions"}],"predecessor-version":[{"id":4018,"href":"https:\/\/casadovereador.com\/en\/wp-json\/wp\/v2\/custom_blocks\/1058\/revisions\/4018"}],"wp:attachment":[{"href":"https:\/\/casadovereador.com\/en\/wp-json\/wp\/v2\/media?parent=1058"}],"wp:term":[{"taxonomy":"custom_blocks_category","embeddable":true,"href":"https:\/\/casadovereador.com\/en\/wp-json\/wp\/v2\/custom_blocks_category?post=1058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}